{"id":30529,"date":"2022-08-14T12:10:39","date_gmt":"2022-08-14T15:10:39","guid":{"rendered":"https:\/\/actualizateiguazu.com\/v3\/?p=30529"},"modified":"2022-08-14T12:10:42","modified_gmt":"2022-08-14T15:10:42","slug":"iguazu-buscan-a-milena-zamara-de-14-anos-que-no-regreso-a-su-hogar","status":"publish","type":"post","link":"https:\/\/actualizateiguazu.com\/v3\/2022\/08\/14\/iguazu-buscan-a-milena-zamara-de-14-anos-que-no-regreso-a-su-hogar\/","title":{"rendered":"Iguaz\u00fa: Buscan a Milena Zamara de 14 a\u00f1os que no regreso a su hogar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Seg\u00fan denunci\u00f3 su madre ante la Comisar\u00eda de la Mujer, su hija Milena Zamara Fern\u00e1ndez de 14 a\u00f1os, sali\u00f3 de su domicilio ubicado en el barrio Las Le\u00f1as de esta ciudad el pasado viernes en horas de la tarde con destino a la casa de su padre, residencia donde se estableci\u00f3 que no hab\u00eda llegado, no regresando hasta el momento desconociendose su paradero actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La joven al momento de ausentarse vest\u00eda, pantal\u00f3n rojo con flores, campera de color lila, llevaba consigo una mochila floreada, la misma es de contextura delgada, mide 1,60 metros, ojos marrones, cabello rubio lacios hasta los hombros, tez blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cualquier informaci\u00f3n sobre el paradero de la menor, comunicarse a la l\u00ednea gratuita 101 o dirigirse a la sede policial m\u00e1s cercana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan denunci\u00f3 su madre ante la Comisar\u00eda de la Mujer, su hija Milena Zamara Fern\u00e1ndez<\/p>\n","protected":false},"author":1,"featured_media":30530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,226,228],"tags":[],"class_list":["post-30529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-locales","category-policiales"],"_links":{"self":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/30529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/comments?post=30529"}],"version-history":[{"count":1,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/30529\/revisions"}],"predecessor-version":[{"id":30531,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/30529\/revisions\/30531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/media\/30530"}],"wp:attachment":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/media?parent=30529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/categories?post=30529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/tags?post=30529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}