{"id":51335,"date":"2025-05-20T16:36:04","date_gmt":"2025-05-20T19:36:04","guid":{"rendered":"https:\/\/actualizateiguazu.com\/v3\/?p=51335"},"modified":"2025-05-20T16:36:04","modified_gmt":"2025-05-20T19:36:04","slug":"celebraran-a-la-patria-con-una-pena-folclorica-y-titeres-al-caer-el-sol-en-cataratas","status":"publish","type":"post","link":"https:\/\/actualizateiguazu.com\/v3\/2025\/05\/20\/celebraran-a-la-patria-con-una-pena-folclorica-y-titeres-al-caer-el-sol-en-cataratas\/","title":{"rendered":"Celebrar\u00e1n a la patria con una pe\u00f1a folcl\u00f3rica y t\u00edteres \u00a0\u201cAl caer el sol en Cataratas\u201d"},"content":{"rendered":"<p>Llega la segunda edici\u00f3n de \u201cAl caer en Sol en Cataratas\u201d en esta oportunidad ser\u00e1 una pe\u00f1a para celebrar el cumplea\u00f1os de la patria. Una tarde para compartir y disfrutar en el Anfiteatro del Parque<\/p>\n<p>El pr\u00f3ximo s\u00e1bado 24 de mayo de 2025 se llevar\u00e1 a cabo la segunda edici\u00f3n del evento cultural \u00abAl Caer el Sol en Cataratas\u00bb en conmemoraci\u00f3n al cumplea\u00f1os de la patria 25 de mayo. La propuesta, que naci\u00f3 del trabajo en conjunto entre la Secretar\u00eda de Cultura de Misiones, la Administraci\u00f3n de Parques Nacionales e Iguaz\u00fa Argentina S.A. En esta oportunidad para celebrar un aniversario m\u00e1s de la patria ser\u00e1 en formato una pe\u00f1a folcl\u00f3rica para los visitantes del Parque como para la comunidad local.<\/p>\n<p>La jornada contar\u00e1 con una variada programaci\u00f3n que incluir\u00e1 espect\u00e1culos musicales, teatrales y gastron\u00f3micos, y se llevar\u00e1 a cabo a partir de las 15:30 h hasta las 18:30 h, en la zona del Anfiteatro. La entrada ser\u00e1 libre y gratuita no obstante se busca alcanzar la solidaridad de los asistentes promoviendo la colaboraci\u00f3n con un alimento no perecedero para donar a los merenderos de Puerto Iguaz\u00fa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-51337\" src=\"https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-scaled.jpg 2560w, https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-300x225.jpg 300w, https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-1024x768.jpg 1024w, https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-768x576.jpg 768w, https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-1536x1152.jpg 1536w, https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-2048x1536.jpg 2048w, https:\/\/actualizateiguazu.com\/v3\/wp-content\/uploads\/2025\/05\/IMG_20241129_102756549-1-720x540.jpg 720w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Entre las actividades destacadas, se presentar\u00e1 el Grupo Sacados del Tacho, con su obra de t\u00edteres \u00abSakados al natural\u00bb, que aborda la problem\u00e1tica de los atropellamientos en las rutas y la conservaci\u00f3n del yaguaret\u00e9, especie emblema de la biodiversidad misionera. Adem\u00e1s, el p\u00fablico podr\u00e1 disfrutar del espect\u00e1culo musical del Grupo EKOS, la presentaci\u00f3n del Ballet Municipal \u00abLa Patria al Hombro\u00bb y el Ballet Folcl\u00f3rico \u00abEl Mens\u00fa\u00bb.<\/p>\n<p>En la zona del patio habr\u00e1 una variada oferta gastron\u00f3mica junto a Gaby Chipas y el Restaurante Fort\u00edn, con la preparaci\u00f3n alimentos regionales en vivo. Adem\u00e1s, el evento contar\u00e1 con la estrecha colaboraci\u00f3n de la empresa R\u00edo Uruguay, que habilitar\u00e1 el servicio de traslado gratuito con colectivos que saldr\u00e1n desde Puerto Iguaz\u00fa para facilitar el acceso a todos quienes deseen asistir.<\/p>\n<p>Esta propuesta, cuya primera edici\u00f3n se realiz\u00f3 a finales de marzo y tuvo gran concurrencia, surgi\u00f3 para que toda la comunidad pueda ser parte de jornadas cuyo valor est\u00e1 en reconocerse part\u00edcipes del destino y convertirse en propulsores de la identidad cultural y ambiental de Misiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llega la segunda edici\u00f3n de \u201cAl caer en Sol en Cataratas\u201d en esta oportunidad ser\u00e1<\/p>\n","protected":false},"author":1,"featured_media":51336,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,226],"tags":[],"class_list":["post-51335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-locales"],"_links":{"self":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/51335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/comments?post=51335"}],"version-history":[{"count":1,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/51335\/revisions"}],"predecessor-version":[{"id":51338,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/51335\/revisions\/51338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/media\/51336"}],"wp:attachment":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/media?parent=51335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/categories?post=51335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/tags?post=51335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}