{"id":51700,"date":"2025-06-07T10:17:01","date_gmt":"2025-06-07T13:17:01","guid":{"rendered":"https:\/\/actualizateiguazu.com\/v3\/?p=51700"},"modified":"2025-06-07T10:19:48","modified_gmt":"2025-06-07T13:19:48","slug":"el-transporte-publico-sera-gratuito-en-toda-la-provincia-el-domingo","status":"publish","type":"post","link":"https:\/\/actualizateiguazu.com\/v3\/2025\/06\/07\/el-transporte-publico-sera-gratuito-en-toda-la-provincia-el-domingo\/","title":{"rendered":"El Transporte p\u00fablico ser\u00e1 gratuito en toda la provincia el domingo"},"content":{"rendered":"<div>El gobierno provincial inform\u00f3 que este domingo 8 de junio, durante la jornada electoral, el transporte p\u00fablico ser\u00e1 sin costo en toda la provincia para el usuario. La medida, que rige desde la medianoche del domingo hasta las 23 hs, busca facilitar el traslado de los ciudadanos para el ejercicio democr\u00e1tico.<\/div>\n<div><\/div>\n<div>En el marco de las elecciones provinciales del pr\u00f3ximo domingo 8 de junio, informaron que el transporte p\u00fablico ser\u00e1 libre y gratuito en toda la provincia desde las 00:00 hasta las 23:00 horas. La disposici\u00f3n alcanza a los servicios urbanos, suburbanos e interurbanos operados por empresas que utilicen el sistema de boleto electr\u00f3nico.<\/div>\n<div><\/div>\n<div>\u00a0La medida se comunic\u00f3 a trav\u00e9s de las redes sociales, destacando que el costo del traslado ser\u00e1 cubierto por el Estado provincial. El benficio alcanza a los servicios urbanos, suburbanos e interurbanos de empresas con boleto electr\u00f3nico.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno provincial inform\u00f3 que este domingo 8 de junio, durante la jornada electoral, el<\/p>\n","protected":false},"author":1,"featured_media":51701,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,226],"tags":[],"class_list":["post-51700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-locales"],"_links":{"self":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/51700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/comments?post=51700"}],"version-history":[{"count":3,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/51700\/revisions"}],"predecessor-version":[{"id":51704,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/posts\/51700\/revisions\/51704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/media\/51701"}],"wp:attachment":[{"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/media?parent=51700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/categories?post=51700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actualizateiguazu.com\/v3\/wp-json\/wp\/v2\/tags?post=51700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}